{"id":3623,"date":"2025-03-06T15:40:36","date_gmt":"2025-03-06T15:40:36","guid":{"rendered":"https:\/\/lidomolveno.it\/cookie-policy\/"},"modified":"2025-06-03T09:00:12","modified_gmt":"2025-06-03T09:00:12","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; top_padding_tablet=&#8221;100px&#8221; bottom_padding_tablet=&#8221;60px&#8221; left_padding_tablet=&#8221;60px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;60px&#8221; bottom_padding_phone=&#8221;30px&#8221; left_padding_phone=&#8221;30px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_js]JTNDc2NyaXB0JTIwdHlwZSUzRCUyN21vZHVsZSUyNyUyMHNyYyUzRCUyMmh0dHBzJTNBJTJGJTJGdGVzdC5hdmFjeXN0YWdpbmctY2RuLmNvbSUyRmF2YWN5LWNvbXBvbmVudHMlMkZjb21wb25lbnRzJTJGY29tcG9uZW50cy5lc20uanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0Nhdi1wb2xpY3ktdmlld2VyJTIwcG9saWN5LXVybCUzRCUyMmh0dHBzJTNBJTJGJTJGYXBpLmF2YWN5LmV1JTJGcGxhc21lZGlhJTJGY29va2llcG9saWN5JTJGMjUlMkZlbiUyMiUzRSUzQyUyRmF2LXBvbGljeS12aWV3ZXIlM0U=[\/vc_raw_js][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; top_padding_tablet=&#8221;100px&#8221; bottom_padding_tablet=&#8221;60px&#8221; left_padding_tablet=&#8221;60px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;60px&#8221; bottom_padding_phone=&#8221;30px&#8221; left_padding_phone=&#8221;30px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3623","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy - Hotel Lido Molveno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy - Hotel Lido Molveno\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; top_padding_tablet=&#8221;100px&#8221; bottom_padding_tablet=&#8221;60px&#8221; left_padding_tablet=&#8221;60px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;60px&#8221; bottom_padding_phone=&#8221;30px&#8221; left_padding_phone=&#8221;30px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Lido Molveno\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T09:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/\",\"url\":\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/\",\"name\":\"Cookie Policy - Hotel Lido Molveno\",\"isPartOf\":{\"@id\":\"https:\/\/www.lidomolveno.it\/en\/#website\"},\"datePublished\":\"2025-03-06T15:40:36+00:00\",\"dateModified\":\"2025-06-03T09:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lidomolveno.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lidomolveno.it\/en\/#website\",\"url\":\"https:\/\/www.lidomolveno.it\/en\/\",\"name\":\"Hotel Lido Molveno\",\"description\":\"Slow &amp; Natural Living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lidomolveno.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy - Hotel Lido Molveno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/","og_locale":"en_US","og_type":"article","og_title":"Cookie Policy - Hotel Lido Molveno","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; top_padding_tablet=&#8221;100px&#8221; bottom_padding_tablet=&#8221;60px&#8221; left_padding_tablet=&#8221;60px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;60px&#8221; bottom_padding_phone=&#8221;30px&#8221; left_padding_phone=&#8221;30px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;...","og_url":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/","og_site_name":"Hotel Lido Molveno","article_modified_time":"2025-06-03T09:00:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/","url":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/","name":"Cookie Policy - Hotel Lido Molveno","isPartOf":{"@id":"https:\/\/www.lidomolveno.it\/en\/#website"},"datePublished":"2025-03-06T15:40:36+00:00","dateModified":"2025-06-03T09:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidomolveno.it\/en\/cookie-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidomolveno.it\/en\/cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lidomolveno.it\/en\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.lidomolveno.it\/en\/#website","url":"https:\/\/www.lidomolveno.it\/en\/","name":"Hotel Lido Molveno","description":"Slow &amp; Natural Living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidomolveno.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/pages\/3623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/comments?post=3623"}],"version-history":[{"count":2,"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/pages\/3623\/revisions"}],"predecessor-version":[{"id":5056,"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/pages\/3623\/revisions\/5056"}],"wp:attachment":[{"href":"https:\/\/www.lidomolveno.it\/en\/wp-json\/wp\/v2\/media?parent=3623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}